{"id":628,"count":2,"description":"<h2>Fruchtfliegen: Was sind sie und wie wird man sie los?<\/h2>\r\n<p>Fruchtfliegen sind kleine, meist braun-gelbe Fliegen, die vor allem in der N\u00e4he von Fr\u00fcchten und Gem\u00fcse auftreten. Sie sind besonders im Sommer und Herbst ein l\u00e4stiges Problem in vielen Haushalten.<\/p>\r\n<h3>Ursachen f\u00fcr Fruchtfliegenbefall<\/h3>\r\n<p>Die Fliegen legen ihre Eier auf \u00fcberreifen oder besch\u00e4digten Fr\u00fcchten ab, wo sich dann die Larven entwickeln. Auch alte Essensreste oder verunreinigte Abfalleimer k\u00f6nnen Fruchtfliegen anziehen.<\/p>\r\n<h3>Ma\u00dfnahmen zur Vorbeugung und Bek\u00e4mpfung<\/h3>\r\n<p>Um Fruchtfliegenbefall zu vermeiden, sollten \u00fcberreife und besch\u00e4digte Fr\u00fcchte sowie Essensreste und M\u00fcll regelm\u00e4\u00dfig entsorgt werden. Auch das Reinigen von Abfalleimern und Obstschalen kann dazu beitragen, dass sich keine Fliegen ansiedeln.<\/p>\r\n<p>Wenn sich bereits Fruchtfliegen im Haus aufhalten, k\u00f6nnen verschiedene Hausmittel helfen, sie zu bek\u00e4mpfen. Eine Schale mit Essig, Zitrone oder Wein kann die Fliegen anlocken und t\u00f6ten. Auch eine Mischung aus Sp\u00fclmittel und Wasser kann dazu beitragen, dass die Fliegen ertrinken.<\/p>\r\n<p>Es gibt auch spezielle Fruchtfliegenfallen im Handel, die auf nat\u00fcrlichen Wirkstoffen basieren und die Fliegen anlocken und t\u00f6ten.<\/p>\r\n<h3>Fazit<\/h3>\r\n<p>Fruchtfliegen sind zwar l\u00e4stig, k\u00f6nnen aber mit einfachen Mitteln bek\u00e4mpft werden. Durch regelm\u00e4\u00dfiges Entsorgen von Essensresten und das Reinigen von Abfalleimern kann einem Befall vorgebeugt werden.<\/p>","link":"https:\/\/www.naturhaus.com\/magazin\/tag\/fruchtfliegen\/","name":"Fruchtfliegen","slug":"fruchtfliegen","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.naturhaus.com\/magazin\/wp-json\/wp\/v2\/tags\/628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.naturhaus.com\/magazin\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.naturhaus.com\/magazin\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.naturhaus.com\/magazin\/wp-json\/wp\/v2\/posts?tags=628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}